{"id":146,"count":2,"description":"","link":"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/","name":"Battery &amp; Charger","slug":"battery-charger","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Battery &amp; Charger Archives - ELECOM US<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Battery &amp; Charger Archives - ELECOM US\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/\" \/>\n<meta property=\"og:site_name\" content=\"ELECOM US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/\",\"url\":\"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/\",\"name\":\"Battery &amp; Charger Archives - ELECOM US\",\"isPartOf\":{\"@id\":\"https:\/\/elecomus.com\/web\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elecomus.com\/web\/#website\",\"url\":\"https:\/\/elecomus.com\/web\/\",\"name\":\"ELECOM US\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elecomus.com\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Battery &amp; Charger Archives - ELECOM US","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Battery &amp; Charger Archives - ELECOM US","og_url":"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/","og_site_name":"ELECOM US","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/","url":"https:\/\/elecomus.com\/web\/product-category\/battery-charger\/","name":"Battery &amp; Charger Archives - ELECOM US","isPartOf":{"@id":"https:\/\/elecomus.com\/web\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/elecomus.com\/web\/#website","url":"https:\/\/elecomus.com\/web\/","name":"ELECOM US","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elecomus.com\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/elecomus.com\/web\/wp-json\/wp\/v2\/product_cat\/146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elecomus.com\/web\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elecomus.com\/web\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/elecomus.com\/web\/wp-json\/wp\/v2\/product?product_cat=146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}